{"id":9892,"date":"2022-11-21T23:40:30","date_gmt":"2022-11-21T22:40:30","guid":{"rendered":"https:\/\/www.turchini75.com\/v1\/?p=9892"},"modified":"2022-11-22T00:25:28","modified_gmt":"2022-11-21T23:25:28","slug":"qualifies-2","status":"publish","type":"post","link":"https:\/\/www.turchini75.com\/v1\/2022\/11\/21\/qualifies-2\/","title":{"rendered":"Qualifi\u00e9s"},"content":{"rendered":"<p>Pour ce huiti\u00e8me tour de la coupe de France, le Sporting \u00e9tait oppos\u00e9 \u00e0 l\u2019\u00e9quipe de Marnaval club de Saint-Dizier \u00e9voluant en r\u00e9gional 1.<br \/>\nOn se disait \u00e0 l\u2019heure du tirage au sort que ce ne serait qu\u2019une formalit\u00e9 et pourtant ce fut assez compliqu\u00e9.<br \/>\nR\u00e9gis Brouard titularise Boucher dans les buts, une d\u00e9fense avec Sainati, Guidi et N&rsquo;Diaye, on retrouve au milieu Janneh, Ducrocq et Camara, et en attaque Schur, Alfarela et Santelli.<br \/>\nSoutenu par un nombreux public, les locaux se cr\u00e9ent des occasions et inqui\u00e8tent Boucher notamment par G\u00e9rard. Le gardien Bastiais devra sortir le grand jeu pour \u00e9viter que son \u00e9quipe n\u2019encaisse de but.<br \/>\nLes Bastiais sont, \u00e0 l\u2019image de leurs derni\u00e8res prestations, assez brouillons et incapables d\u2019inqui\u00e9ter v\u00e9ritablement l\u2019arri\u00e8re garde de Marnaval.<br \/>\nMi temps 0-0, on se demande alors comment le match va tourner et si les locaux vont garder le rythme\u2026<br \/>\nOn aura la r\u00e9ponse \u00e0 29 minutes de la fin lorsqu&rsquo;\u00e0 la suite d\u2019un ballon en profondeur, Schur \u00e9limine le gardien et vient ouvrir le score. 0-1 et puis rapidement 0-2 par Santelli, sur un centre de Van den Kerkhof, alors que Alfarela cl\u00f4ture la marque dans les arr\u00eats de jeu, 0-3.<br \/>\nUne qualification qui donc aura mis du temps \u00e0 se dessiner, mais l\u2019essentiel est fait. Le Sporting est qualifi\u00e9 pour les 32\u00e8mes de finale de la coupe de France, o\u00f9 il affrontera Evreux, \u00e9quipe de national 2 en Normandie, rendez-vous d\u00e9but janvier pour cette confrontation.<br \/>\nRetour en championnat \u00e0 la fin d\u00e9cembre apr\u00e8s la coupe du monde, il faudra recharger les batteries lors de cette interruption, avant d\u2019attaquer la deuxi\u00e8me partie de championnat, en recevant Caen \u00e0 huis clos, ce qui ne sera pas simple\u2026<\/p>\n<p>FORZA BASTIA !!!<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_9892\" class=\"pvc_stats total_only  \" data-element-id=\"9892\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.turchini75.com\/v1\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pour ce huiti\u00e8me tour de la coupe de France, le Sporting \u00e9tait oppos\u00e9 \u00e0 l\u2019\u00e9quipe de Marnaval club de Saint-Dizier \u00e9voluant en r\u00e9gional [&hellip;]<\/p>\n","protected":false},"author":499,"featured_media":9893,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[994,1028,1029,866,913],"class_list":["post-9892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","tag-boucher","tag-gerard","tag-royer","tag-santelli","tag-schur"],"a3_pvc":{"activated":true,"total_views":87,"today_views":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts\/9892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/users\/499"}],"replies":[{"embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/comments?post=9892"}],"version-history":[{"count":3,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts\/9892\/revisions"}],"predecessor-version":[{"id":9896,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts\/9892\/revisions\/9896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/media\/9893"}],"wp:attachment":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/media?parent=9892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/categories?post=9892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/tags?post=9892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}