{"id":7279,"date":"2017-09-25T23:07:56","date_gmt":"2017-09-25T21:07:56","guid":{"rendered":"http:\/\/www.turchini75.com\/v1\/?p=7279"},"modified":"2017-09-25T23:07:56","modified_gmt":"2017-09-25T21:07:56","slug":"communique","status":"publish","type":"post","link":"https:\/\/www.turchini75.com\/v1\/2017\/09\/25\/communique\/","title":{"rendered":"COMMUNIQU\u00c9"},"content":{"rendered":"<p>Corses, amis de la Corse et supporters du SC Bastia.<\/p>\n<p>Le Club des supporters du SC Bastia \u00e0 Paris a \u00e9t\u00e9 cr\u00e9\u00e9 en 1972. Sa principale action a toujours \u00e9t\u00e9 d&rsquo;apporter, sous les conditions strictes de la loi de 1901, un soutien inconditionnel au Sporting Club de Bastia.<br \/>\nDurant toutes ces ann\u00e9es, de tr\u00e8s nombreux d\u00e9placements et autres manifestations d&rsquo;appui au club bastiais ont \u00e9t\u00e9 r\u00e9alis\u00e9s avec succ\u00e8s, sans le moindre incident.<br \/>\nAu terme de la saison 2016 \/ 2017, les instances du football professionnel ont d\u00e9cid\u00e9 de r\u00e9trograder le club de la Haute-Corse en National 3, et de le priver de facto du statut de club professionnel. Nous prenons acte. Nous ne reviendrons pas sur ce d\u00e9sastre, et nous n&rsquo;apporterons aucun nouveau commentaire sur les faits qui ont pr\u00e9cipit\u00e9 notre club dans le trou. Tout a \u00e9t\u00e9 dit et les responsabilit\u00e9s connues de tous.<br \/>\nA l&rsquo;aube de cette nouvelle \u00e8re,  \u00e0 ce qui pourra s&rsquo;apparenter au d\u00e9but d&rsquo;une travers\u00e9e du d\u00e9sert, le Club des supporters du SC Bastia \u00e0 Paris poursuivra sa t\u00e2che, sa mission qu&rsquo;est la sienne.  Il n&rsquo;y aura pas d&rsquo;interruption, mais une continuit\u00e9 dans l&rsquo;action. En un mot comme en cent, p\u00e9renniser l&rsquo;association pour se ranger derri\u00e8re le Sporting.<br \/>\nPour ce faire, nous continuerons \u00e0 soutenir le club dans les comp\u00e9titions pour qu&rsquo;il puisse gravir les \u00e9chelons qui l&rsquo;am\u00e8neront \u00e0 retrouver le rang qu&rsquo;il n&rsquo;aurait jamais d\u00fb quitter. La nouvelle \u00e9quipe dirigeante, si r\u00e9duite soit-elle, pr\u00e9sente certaines garanties. Nous vous invitons \u00e0 rester toujours \u00e0 l&rsquo;\u00e9coute de notre association, aux actions qu&rsquo;elle m\u00e8nera. Tout nous pousse \u00e0 croire que vos soutiens, seront toujours, comme depuis quarante-cinq ans, d&rsquo;une aide pr\u00e9cieuse.<\/p>\n<p>Un cappieremu mica !<br \/>\nForza Bastia !<\/p>\n<p>                                                                                          Pierre VINCIGUERRA<br \/>\n                                                                                  Pr\u00e9sident du Club des supporters du S.C Bastia \u00e0 Paris<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_7279\" class=\"pvc_stats total_only  \" data-element-id=\"7279\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.turchini75.com\/v1\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Corses, amis de la Corse et supporters du SC Bastia. Le Club des supporters du SC Bastia \u00e0 Paris a \u00e9t\u00e9 cr\u00e9\u00e9 en [&hellip;]<\/p>\n","protected":false},"author":499,"featured_media":7280,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[26,155,696,695],"class_list":["post-7279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","tag-association","tag-bastia","tag-president","tag-soutien"],"a3_pvc":{"activated":true,"total_views":45,"today_views":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts\/7279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/users\/499"}],"replies":[{"embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/comments?post=7279"}],"version-history":[{"count":0,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts\/7279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/media\/7280"}],"wp:attachment":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/media?parent=7279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/categories?post=7279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/tags?post=7279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}