{"id":10407,"date":"2023-09-18T21:23:45","date_gmt":"2023-09-18T19:23:45","guid":{"rendered":"https:\/\/www.turchini75.com\/v1\/?p=10407"},"modified":"2023-09-24T22:49:53","modified_gmt":"2023-09-24T20:49:53","slug":"aux-abonnes-absents-2","status":"publish","type":"post","link":"https:\/\/www.turchini75.com\/v1\/2023\/09\/18\/aux-abonnes-absents-2\/","title":{"rendered":"Aux abonn\u00e9s absents !"},"content":{"rendered":"<p>Apr\u00e8s 15 jours de tr\u00eave internationale, le Sporting retrouve Furiani et une \u00e9quipe de Laval bien class\u00e9e qui ne lui a gu\u00e8re souri la saison pass\u00e9e avec 2 d\u00e9faites.<br \/>\nR\u00e9gis Brouard r\u00e9cup\u00e8re Ducrocq et Vincent, mais Placide est toujours suspendu, les nouvelles recrues sont \u00e9galement pr\u00e9sentes.<br \/>\nBeaucoup de monde encore dans les tribunes avec plus de 12 300 spectateurs qui attendent la victoire des leurs !<br \/>\nLe Sporting rentre bien dans le match et se cr\u00e9e la premi\u00e8re occasion par Tavares mais son tir n&rsquo;inqui\u00e8te pas le gardien Lavallois.<br \/>\nLes Bleus contr\u00f4lent le ballon mais se montrent incapables d&rsquo;inqui\u00e9ter l&rsquo;arri\u00e8re garde Mayennaise et \u00e0 la demi heure de jeu, Roye bien seul aux 18 m\u00e8tres ouvre le score d&rsquo;une reprise de vol\u00e9e.<br \/>\n1-0 mi temps.<br \/>\nOn esp\u00e8re une grosse r\u00e9action Bastiaise, mais coup de massue Drame marque contre son camp 0-2, les Bleus ont pris un gros coup sur la t\u00eate, Laval rajoute m\u00eame un troisi\u00e8me but quelques minutes plus tard, la messe est dite malgr\u00e9 quelques occasions avec la rentr\u00e9e de Conte notamment, on en restera l\u00e0.<br \/>\nCruelle d\u00e9sillusion avec des Bastiais incapables de r\u00e9agir, et domin\u00e9s dans tous les compartiments du jeu.<br \/>\nM\u00eame si le coach endossera la responsabilit\u00e9 de la d\u00e9faite, les joueurs doivent une revanche \u00e0 leurs supporters, d\u00e8s samedi \u00e0 Angers, ce qui ne sera pas simple&#8230;<\/p>\n<p>Forza Bastia !!!<\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_10407\" class=\"pvc_stats total_only  \" data-element-id=\"10407\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.0\" viewBox=\"0 0 502 315\" preserveAspectRatio=\"xMidYMid meet\"><g transform=\"translate(0,332) scale(0.1,-0.1)\" fill=\"\" stroke=\"none\"><path d=\"M2394 3279 l-29 -30 -3 -207 c-2 -182 0 -211 15 -242 39 -76 157 -76 196 0 15 31 17 60 15 243 l-3 209 -33 29 c-26 23 -41 29 -80 29 -41 0 -53 -5 -78 -31z\"\/><path d=\"M3085 3251 c-45 -19 -58 -50 -96 -229 -47 -217 -49 -260 -13 -295 52 -53 146 -42 177 20 16 31 87 366 87 410 0 70 -86 122 -155 94z\"\/><path d=\"M1751 3234 c-13 -9 -29 -31 -37 -50 -12 -29 -10 -49 21 -204 19 -94 39 -189 45 -210 14 -50 54 -80 110 -80 34 0 48 6 76 34 21 21 34 44 34 59 0 14 -18 113 -40 219 -37 178 -43 195 -70 221 -36 32 -101 37 -139 11z\"\/><path d=\"M1163 3073 c-36 -7 -73 -59 -73 -102 0 -56 133 -378 171 -413 34 -32 83 -37 129 -13 70 36 67 87 -16 290 -86 209 -89 214 -129 231 -35 14 -42 15 -82 7z\"\/><path d=\"M3689 3066 c-15 -9 -33 -30 -42 -48 -48 -103 -147 -355 -147 -375 0 -98 131 -148 192 -74 13 15 57 108 97 206 80 196 84 226 37 273 -30 30 -99 39 -137 18z\"\/><path d=\"M583 2784 c-38 -19 -67 -74 -58 -113 9 -42 211 -354 242 -373 16 -10 45 -18 66 -18 51 0 107 52 107 100 0 39 -1 41 -124 234 -80 126 -108 162 -133 173 -41 17 -61 16 -100 -3z\"\/><path d=\"M4250 2784 c-14 -9 -74 -91 -133 -183 -95 -150 -107 -173 -107 -213 0 -55 33 -94 87 -104 67 -13 90 8 211 198 130 202 137 225 78 284 -27 27 -42 34 -72 34 -22 0 -50 -8 -64 -16z\"\/><path d=\"M2275 2693 c-553 -48 -1095 -270 -1585 -649 -135 -104 -459 -423 -483 -476 -23 -49 -22 -139 2 -186 73 -142 361 -457 571 -626 285 -228 642 -407 990 -497 242 -63 336 -73 660 -74 310 0 370 5 595 52 535 111 1045 392 1455 803 122 121 250 273 275 326 19 41 19 137 0 174 -41 79 -309 363 -465 492 -447 370 -946 591 -1479 653 -113 14 -422 18 -536 8z m395 -428 c171 -34 330 -124 456 -258 112 -119 167 -219 211 -378 27 -96 24 -300 -5 -401 -72 -255 -236 -447 -474 -557 -132 -62 -201 -76 -368 -76 -167 0 -236 14 -368 76 -213 98 -373 271 -451 485 -162 444 86 934 547 1084 153 49 292 57 452 25z m909 -232 c222 -123 408 -262 593 -441 76 -74 138 -139 138 -144 0 -16 -233 -242 -330 -319 -155 -123 -309 -223 -461 -299 l-81 -41 32 46 c18 26 49 83 70 128 143 306 141 649 -6 957 -25 52 -61 116 -79 142 l-34 47 45 -20 c26 -10 76 -36 113 -56z m-2057 25 c-40 -58 -105 -190 -130 -263 -110 -324 -59 -707 132 -981 25 -35 42 -64 37 -64 -19 0 -241 119 -326 174 -188 122 -406 314 -532 468 l-58 71 108 103 c185 178 428 349 672 473 66 33 121 60 123 61 2 0 -10 -19 -26 -42z\"\/><path d=\"M2375 1950 c-198 -44 -350 -190 -395 -379 -18 -76 -8 -221 19 -290 114 -284 457 -406 731 -260 98 52 188 154 231 260 27 69 37 214 19 290 -38 163 -166 304 -326 360 -67 23 -215 33 -279 19z\"\/><\/g><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.turchini75.com\/v1\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s 15 jours de tr\u00eave internationale, le Sporting retrouve Furiani et une \u00e9quipe de Laval bien class\u00e9e qui ne lui a gu\u00e8re souri [&hellip;]<\/p>\n","protected":false},"author":499,"featured_media":10408,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[994,1084,1093,866,1013],"class_list":["post-10407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualite","tag-boucher","tag-drame","tag-roye","tag-santelli","tag-vargas"],"a3_pvc":{"activated":true,"total_views":67,"today_views":0},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts\/10407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/users\/499"}],"replies":[{"embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/comments?post=10407"}],"version-history":[{"count":3,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts\/10407\/revisions"}],"predecessor-version":[{"id":10413,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/posts\/10407\/revisions\/10413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/media\/10408"}],"wp:attachment":[{"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/media?parent=10407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/categories?post=10407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.turchini75.com\/v1\/wp-json\/wp\/v2\/tags?post=10407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}